{"id":244244,"date":"2024-11-11T11:19:53","date_gmt":"2024-11-11T10:19:53","guid":{"rendered":"https:\/\/www.secondastrada.com\/it\/pantaloni-gant-blu-3\/"},"modified":"2026-02-26T15:06:01","modified_gmt":"2026-02-26T14:06:01","slug":"pantaloni-gant-blu-3","status":"publish","type":"product","link":"https:\/\/www.secondastrada.com\/it\/pantaloni-gant-blu-3\/","title":{"rendered":"Pantaloni Gant Blu"},"content":{"rendered":"<p>Pantaloni eleganti in simil velluto ed in total blu navy. Presenti tasche a taglio trasversale sul fronte pi\u00f9 tasche a taglio con bottone sul retro. La vestibilit\u00e0 \u00e8 morbida e pratica grazie a bottone pi\u00f9 zip. I pantaloni sono adatti per occasioni casual\/eleganti e facilmente combinabili. Indossali per essere impeccabile.<br \/>Cod. art. 2203 1500190 SV<br \/>Vi ricordiamo che tutti i nostri articoli sono originali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pantaloni eleganti in simil velluto ed in total blu navy. Presenti tasche a taglio trasversale sul fronte pi\u00f9 tasche a taglio con bottone sul retro. La vestibilit\u00e0 \u00e8 morbida e pratica grazie a bottone pi\u00f9 zip. I pantaloni sono adatti per occasioni casual\/eleganti e facilmente combinabili. Indossali per essere impeccabile.Cod. art. 2203 1500190 SVVi ricordiamo&#8230;<\/p>\n","protected":false},"featured_media":194532,"template":"","meta":{"inline_featured_image":false},"ss_brand":[1896],"ss_promo":[2182],"ss_season":[2189],"product_cat":[1332,1484,2254,1714],"product_tag":[1736,2140],"class_list":{"0":"post-244244","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"ss_brand-gant-uomo","7":"ss_promo-ultime-occasioni-uomo","8":"ss_season-ai24","9":"product_cat-abbigliamento-uomo","10":"product_cat-pantaloni-da-uomo","11":"product_cat-pantaloni-eleganti-da-uomo","12":"product_cat-collezione-uomo","13":"product_tag-pantaloni-gant-uomo","14":"product_tag-ultime-occasioni-uomo","16":"first","17":"instock","18":"sale","19":"shipping-taxable","20":"purchasable","21":"product-type-variable","22":"has-default-attributes"},"acf":{"ss_brand":[{"term_id":1896,"name":"GANT","slug":"gant-uomo","term_group":0,"term_taxonomy_id":1896,"taxonomy":"ss_brand","description":"Eleganza e comfort sono i tratti distintivi della filosofia di Gant. Scopri le collezioni del brand casual-chic pi\u00f9 cool in offerta nel nostro esclusivo store online di grandi firme!\u00a0Acquista online su SecondaStrada.com abbigliamento da uomo Gant scontatissimo!","parent":1268,"count":219,"filter":"raw"}],"ss_promo":[2182],"ss_season":[{"term_id":2189,"name":"AI24","slug":"ai24","term_group":0,"term_taxonomy_id":2189,"taxonomy":"ss_season","description":"","parent":0,"count":2126,"filter":"raw"}],"ss_old_price":"147,00","ss_omnibus_price":"0,00","ss_style_advice":"<p>Pantaloni eleganti in simil velluto ed in total blu navy. Presenti tasche a taglio trasversale sul fronte pi\u00f9 tasche a taglio con bottone sul retro. La vestibilit\u00e0 \u00e8 morbida e pratica grazie a bottone pi\u00f9 zip. I pantaloni sono adatti per occasioni casual\/eleganti e facilmente combinabili. Indossali per essere impeccabile.<br \/>Cod. art. 2203 1500190 SV<br \/>Vi ricordiamo che tutti i nostri articoli sono originali.<\/p>\n","ss_composition":"<p>98% cotone 2% elastane<\/p>\n","ss_fit":"<p>Il modello \u00e8 alto 178 cm e indossa la taglia 32 US corrispondente alla 46 italiana. La vestibilit\u00e0 del capo \u00e8 regolare<\/p>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pantaloni Gant Blu - Acquista online! - Seconda Strada<\/title>\n<meta name=\"description\" content=\"Pantaloni Gant Blu \u27a4 Acquista online su Secondastrada.com Pantaloni Gant Blu \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.secondastrada.com\/it\/pantaloni-gant-blu-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pantaloni Gant Blu - Acquista online! - Seconda Strada\" \/>\n<meta property=\"og:description\" content=\"Pantaloni Gant Blu \u27a4 Acquista online su Secondastrada.com Pantaloni Gant Blu \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.secondastrada.com\/it\/pantaloni-gant-blu-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Seconda Strada\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T14:06:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2024\/09\/2203-1500190-SV_NAVY_AI24_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pantaloni Gant Blu - Acquista online! - Seconda Strada","description":"Pantaloni Gant Blu \u27a4 Acquista online su Secondastrada.com Pantaloni Gant Blu \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.secondastrada.com\/it\/pantaloni-gant-blu-3\/","og_locale":"it_IT","og_type":"article","og_title":"Pantaloni Gant Blu - Acquista online! - Seconda Strada","og_description":"Pantaloni Gant Blu \u27a4 Acquista online su Secondastrada.com Pantaloni Gant Blu \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","og_url":"https:\/\/www.secondastrada.com\/it\/pantaloni-gant-blu-3\/","og_site_name":"Seconda Strada","article_modified_time":"2026-02-26T14:06:01+00:00","og_image":[{"width":1000,"height":1300,"url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2024\/09\/2203-1500190-SV_NAVY_AI24_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.secondastrada.com\/it\/pantaloni-gant-blu-3\/","url":"https:\/\/www.secondastrada.com\/it\/pantaloni-gant-blu-3\/","name":"Pantaloni Gant Blu - Acquista online! - Seconda Strada","isPartOf":{"@id":"https:\/\/www.secondastrada.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.secondastrada.com\/it\/pantaloni-gant-blu-3\/#primaryimage"},"image":{"@id":"https:\/\/www.secondastrada.com\/it\/pantaloni-gant-blu-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2024\/09\/2203-1500190-SV_NAVY_AI24_1.jpg","datePublished":"2024-11-11T10:19:53+00:00","dateModified":"2026-02-26T14:06:01+00:00","description":"Pantaloni Gant Blu \u27a4 Acquista online su Secondastrada.com Pantaloni Gant Blu \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","breadcrumb":{"@id":"https:\/\/www.secondastrada.com\/it\/pantaloni-gant-blu-3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.secondastrada.com\/it\/pantaloni-gant-blu-3\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secondastrada.com\/it\/pantaloni-gant-blu-3\/#primaryimage","url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2024\/09\/2203-1500190-SV_NAVY_AI24_1.jpg","contentUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2024\/09\/2203-1500190-SV_NAVY_AI24_1.jpg","width":1000,"height":1300,"caption":"2203-1500190-SV_NAVY_AI24"},{"@type":"BreadcrumbList","@id":"https:\/\/www.secondastrada.com\/it\/pantaloni-gant-blu-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.secondastrada.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.secondastrada.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Uomo","item":"https:\/\/www.secondastrada.com\/it\/collezione-uomo\/"},{"@type":"ListItem","position":4,"name":"Abbigliamento","item":"https:\/\/www.secondastrada.com\/it\/collezione-uomo\/abbigliamento-uomo\/"},{"@type":"ListItem","position":5,"name":"Pantaloni","item":"https:\/\/www.secondastrada.com\/it\/collezione-uomo\/abbigliamento-uomo\/pantaloni-da-uomo\/"},{"@type":"ListItem","position":6,"name":"Pantaloni eleganti","item":"https:\/\/www.secondastrada.com\/it\/collezione-uomo\/abbigliamento-uomo\/pantaloni-da-uomo\/pantaloni-eleganti-da-uomo\/"},{"@type":"ListItem","position":7,"name":"Pantaloni Gant Blu"}]},{"@type":"WebSite","@id":"https:\/\/www.secondastrada.com\/it\/#website","url":"https:\/\/www.secondastrada.com\/it\/","name":"Seconda Strada","description":"","publisher":{"@id":"https:\/\/www.secondastrada.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.secondastrada.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.secondastrada.com\/it\/#organization","name":"Seconda Strada","url":"https:\/\/www.secondastrada.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secondastrada.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2023\/11\/secondastrada-logo.svg","contentUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2023\/11\/secondastrada-logo.svg","width":353,"height":47,"caption":"Seconda Strada"},"image":{"@id":"https:\/\/www.secondastrada.com\/it\/#\/schema\/logo\/image\/"}}]}},"df_price":35.196,"df_sale_price":"","df_regular_price":35.196,"df_image_link":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2024\/09\/2203-1500190-SV_NAVY_AI24_1-300x300.jpg","_links":{"self":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product\/244244"}],"collection":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/media\/194532"}],"wp:attachment":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/media?parent=244244"}],"wp:term":[{"taxonomy":"ss_brand","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_brand?post=244244"},{"taxonomy":"ss_promo","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_promo?post=244244"},{"taxonomy":"ss_season","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_season?post=244244"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product_cat?post=244244"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product_tag?post=244244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}