{"id":251293,"date":"2025-03-12T14:15:42","date_gmt":"2025-03-12T13:15:42","guid":{"rendered":"https:\/\/www.secondastrada.com\/it\/pantaloni-patrizia-pepe-grigio\/"},"modified":"2026-02-26T14:54:05","modified_gmt":"2026-02-26T13:54:05","slug":"pantaloni-patrizia-pepe-grigio","status":"publish","type":"product","link":"https:\/\/www.secondastrada.com\/it\/pantaloni-patrizia-pepe-grigio\/","title":{"rendered":"Pantaloni  Patrizia Pepe Grigio"},"content":{"rendered":"<p>Pantaloni eleganti in total grigio perla con tasche a taglio trasversale. La vestibilit\u00e0 \u00e8 morbida e pratica grazie a bottone pi\u00f9 zip. I pantaloni sono adatti per occasioni casual\/raffinate. Indossali per essere impeccabile.<br \/>Cod. art. 2P1560 A353 SZ<br \/>Vi ricordiamo che tutti i nostri articoli sono originali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pantaloni eleganti in total grigio perla con tasche a taglio trasversale. La vestibilit\u00e0 \u00e8 morbida e pratica grazie a bottone pi\u00f9 zip. I pantaloni sono adatti per occasioni casual\/raffinate. Indossali per essere impeccabile.Cod. art. 2P1560 A353 SZVi ricordiamo che tutti i nostri articoli sono originali.<\/p>\n","protected":false},"featured_media":251244,"template":"","meta":{"inline_featured_image":false},"ss_brand":[2380],"ss_promo":[2181],"ss_season":[2375],"product_cat":[1329,1658,1342,1635,1634],"product_tag":[2139],"class_list":{"0":"post-251293","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"ss_brand-patrizia-pepe-donna","7":"ss_promo-ultime-occasioni-donna","8":"ss_season-pe25","9":"product_cat-abbigliamento-donna","10":"product_cat-collezione-donna","11":"product_cat-pantaloni-da-donna","12":"product_cat-pantaloni-eleganti-da-donna","13":"product_cat-pantaloni-da-donna-larghi-da-donna","14":"product_tag-ultime-occasioni-donna","16":"first","17":"instock","18":"sale","19":"shipping-taxable","20":"purchasable","21":"product-type-variable","22":"has-default-attributes"},"acf":{"ss_brand":[{"term_id":2380,"name":"PATRIZIA PEPE","slug":"patrizia-pepe-donna","term_group":0,"term_taxonomy_id":2380,"taxonomy":"ss_brand","description":"","parent":1201,"count":42,"filter":"raw"}],"ss_promo":[2181],"ss_season":[{"term_id":2375,"name":"PE25","slug":"pe25","term_group":0,"term_taxonomy_id":2375,"taxonomy":"ss_season","description":"","parent":0,"count":2501,"filter":"raw"}],"ss_old_price":"228,00","ss_omnibus_price":"0,00","ss_style_advice":"<p>Pantaloni eleganti in total grigio perla con tasche a taglio trasversale. La vestibilit\u00e0 \u00e8 morbida e pratica grazie a bottone pi\u00f9 zip. I pantaloni sono adatti per occasioni casual\/raffinate. Indossali per essere impeccabile.<br \/>Cod. art. 2P1560 A353 SZ<br \/>Vi ricordiamo che tutti i nostri articoli sono originali.<\/p>\n","ss_composition":"<p>67% poliestere 31% viscosa 2% elastane<\/p>\n","ss_fit":"<p>La modella \u00e8 alta 172 cm e indossa la taglia 42. La vestibilit\u00e0 del capo \u00e8 regolare.<\/p>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pantaloni Patrizia Pepe Grigio - Acquista online! - Seconda Strada<\/title>\n<meta name=\"description\" content=\"Pantaloni Patrizia Pepe Grigio \u27a4 Acquista online su Secondastrada.com Pantaloni Patrizia Pepe Grigio \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.secondastrada.com\/it\/pantaloni-patrizia-pepe-grigio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pantaloni Patrizia Pepe Grigio - Acquista online! - Seconda Strada\" \/>\n<meta property=\"og:description\" content=\"Pantaloni Patrizia Pepe Grigio \u27a4 Acquista online su Secondastrada.com Pantaloni Patrizia Pepe Grigio \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.secondastrada.com\/it\/pantaloni-patrizia-pepe-grigio\/\" \/>\n<meta property=\"og:site_name\" content=\"Seconda Strada\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T13:54:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2025\/03\/2P1560-A353-SZ_W356_PE25_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pantaloni Patrizia Pepe Grigio - Acquista online! - Seconda Strada","description":"Pantaloni Patrizia Pepe Grigio \u27a4 Acquista online su Secondastrada.com Pantaloni Patrizia Pepe Grigio \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.secondastrada.com\/it\/pantaloni-patrizia-pepe-grigio\/","og_locale":"it_IT","og_type":"article","og_title":"Pantaloni Patrizia Pepe Grigio - Acquista online! - Seconda Strada","og_description":"Pantaloni Patrizia Pepe Grigio \u27a4 Acquista online su Secondastrada.com Pantaloni Patrizia Pepe Grigio \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","og_url":"https:\/\/www.secondastrada.com\/it\/pantaloni-patrizia-pepe-grigio\/","og_site_name":"Seconda Strada","article_modified_time":"2026-02-26T13:54:05+00:00","og_image":[{"width":1000,"height":1300,"url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2025\/03\/2P1560-A353-SZ_W356_PE25_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.secondastrada.com\/it\/pantaloni-patrizia-pepe-grigio\/","url":"https:\/\/www.secondastrada.com\/it\/pantaloni-patrizia-pepe-grigio\/","name":"Pantaloni Patrizia Pepe Grigio - Acquista online! - Seconda Strada","isPartOf":{"@id":"https:\/\/www.secondastrada.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.secondastrada.com\/it\/pantaloni-patrizia-pepe-grigio\/#primaryimage"},"image":{"@id":"https:\/\/www.secondastrada.com\/it\/pantaloni-patrizia-pepe-grigio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2025\/03\/2P1560-A353-SZ_W356_PE25_1.jpg","datePublished":"2025-03-12T13:15:42+00:00","dateModified":"2026-02-26T13:54:05+00:00","description":"Pantaloni Patrizia Pepe Grigio \u27a4 Acquista online su Secondastrada.com Pantaloni Patrizia Pepe Grigio \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","breadcrumb":{"@id":"https:\/\/www.secondastrada.com\/it\/pantaloni-patrizia-pepe-grigio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.secondastrada.com\/it\/pantaloni-patrizia-pepe-grigio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secondastrada.com\/it\/pantaloni-patrizia-pepe-grigio\/#primaryimage","url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2025\/03\/2P1560-A353-SZ_W356_PE25_1.jpg","contentUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2025\/03\/2P1560-A353-SZ_W356_PE25_1.jpg","width":1000,"height":1300,"caption":"2P1560-A353-SZ_W356_PE25"},{"@type":"BreadcrumbList","@id":"https:\/\/www.secondastrada.com\/it\/pantaloni-patrizia-pepe-grigio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.secondastrada.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.secondastrada.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Donna","item":"https:\/\/www.secondastrada.com\/it\/collezione-donna\/"},{"@type":"ListItem","position":4,"name":"Abbigliamento","item":"https:\/\/www.secondastrada.com\/it\/collezione-donna\/abbigliamento-donna\/"},{"@type":"ListItem","position":5,"name":"Pantaloni","item":"https:\/\/www.secondastrada.com\/it\/collezione-donna\/abbigliamento-donna\/pantaloni-da-donna\/"},{"@type":"ListItem","position":6,"name":"Pantaloni eleganti","item":"https:\/\/www.secondastrada.com\/it\/collezione-donna\/abbigliamento-donna\/pantaloni-da-donna\/pantaloni-eleganti-da-donna\/"},{"@type":"ListItem","position":7,"name":"Pantaloni Patrizia Pepe Grigio"}]},{"@type":"WebSite","@id":"https:\/\/www.secondastrada.com\/it\/#website","url":"https:\/\/www.secondastrada.com\/it\/","name":"Seconda Strada","description":"","publisher":{"@id":"https:\/\/www.secondastrada.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.secondastrada.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.secondastrada.com\/it\/#organization","name":"Seconda Strada","url":"https:\/\/www.secondastrada.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secondastrada.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2023\/11\/secondastrada-logo.svg","contentUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2023\/11\/secondastrada-logo.svg","width":353,"height":47,"caption":"Seconda Strada"},"image":{"@id":"https:\/\/www.secondastrada.com\/it\/#\/schema\/logo\/image\/"}}]}},"df_price":45.996,"df_sale_price":"","df_regular_price":45.996,"df_image_link":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2025\/03\/2P1560-A353-SZ_W356_PE25_1-300x300.jpg","_links":{"self":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product\/251293"}],"collection":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/media\/251244"}],"wp:attachment":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/media?parent=251293"}],"wp:term":[{"taxonomy":"ss_brand","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_brand?post=251293"},{"taxonomy":"ss_promo","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_promo?post=251293"},{"taxonomy":"ss_season","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_season?post=251293"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product_cat?post=251293"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product_tag?post=251293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}