{"id":320115,"date":"2025-11-20T10:41:17","date_gmt":"2025-11-20T09:41:17","guid":{"rendered":"https:\/\/www.secondastrada.com\/it\/maglione-materica-marrone-4\/"},"modified":"2026-03-25T13:19:42","modified_gmt":"2026-03-25T12:19:42","slug":"maglione-materica-marrone-4","status":"publish","type":"product","link":"https:\/\/www.secondastrada.com\/it\/maglione-materica-marrone-4\/","title":{"rendered":"Maglione Materica Marrone"},"content":{"rendered":"<p>Maglione costina con girocollo classico, in total marrone testa di moro e frill in tinta applicato sulle maniche. La vestibilit\u00e0 \u00e8 morbida e regolare. Il maglione \u00e8 adatto per occasioni casual e facilmente combinabile. Praticit\u00e0 e stile in un solo capo.<br \/>Cod. art. D018 OA<br \/>Cod. art.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maglione costina con girocollo classico, in total marrone testa di moro e frill in tinta applicato sulle maniche. La vestibilit\u00e0 \u00e8 morbida e regolare. Il maglione \u00e8 adatto per occasioni casual e facilmente combinabile. Praticit\u00e0 e stile in un solo capo.Cod. art. D018 OACod. art.<\/p>\n","protected":false},"featured_media":319386,"template":"","meta":{"inline_featured_image":false},"ss_brand":[2221],"ss_promo":[2181],"ss_season":[2431],"product_cat":[1329,1658,1605,1603,1535],"product_tag":[2204],"class_list":{"0":"post-320115","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"ss_brand-materica-donna","7":"ss_promo-ultime-occasioni-donna","8":"ss_season-ai25","9":"product_cat-abbigliamento-donna","10":"product_cat-collezione-donna","11":"product_cat-maglie-a-manica-lunga-da-donna","12":"product_cat-maglie-girocollo-da-donna","13":"product_cat-maglie-da-donna","14":"product_tag-idee-regalo-donna","16":"first","17":"instock","18":"sale","19":"shipping-taxable","20":"purchasable","21":"product-type-variable","22":"has-default-attributes"},"acf":{"ss_brand":[{"term_id":2221,"name":"MATERICA","slug":"materica-donna","term_group":0,"term_taxonomy_id":2221,"taxonomy":"ss_brand","description":"Materica \u00e8 l\u2019espressione di una femminilit\u00e0 contemporanea, autonoma e consapevole. Dedicato a una donna raffinata e ambiziosa, attenta ai dettagli e alla qualit\u00e0 dei capi che indossa, il brand coniuga il gusto per l\u2019estetica con una profonda ricerca di esclusivit\u00e0, stile e personalit\u00e0.","parent":1201,"count":512,"filter":"raw"}],"ss_promo":[2181],"ss_season":[{"term_id":2431,"name":"AI25","slug":"ai25","term_group":0,"term_taxonomy_id":2431,"taxonomy":"ss_season","description":"","parent":0,"count":2112,"filter":"raw"}],"ss_old_price":"0,00","ss_omnibus_price":"0,00","ss_style_advice":"<p>Maglione costina con girocollo classico, in total marrone testa di moro e frill in tinta applicato sulle maniche. La vestibilit\u00e0 \u00e8 morbida e regolare. Il maglione \u00e8 adatto per occasioni casual e facilmente combinabile. Praticit\u00e0 e stile in un solo capo.<br \/>Cod. art. D018 OA<br \/>Cod. art.<\/p>\n","ss_composition":"<p>55% viscosa 35% poliestere 10% elastane<\/p>\n","ss_fit":"<p>La modella \u00e8 alta 165 cm e indossa la taglia S\/M. La vestibilit\u00e0 del capo \u00e8 regolare.<\/p>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Maglione Materica Marrone - Acquista online! - Seconda Strada<\/title>\n<meta name=\"description\" content=\"Maglione Materica Marrone \u27a4 Acquista online su Secondastrada.com Maglione Materica Marrone \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.secondastrada.com\/it\/maglione-materica-marrone-4\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maglione Materica Marrone - Acquista online! - Seconda Strada\" \/>\n<meta property=\"og:description\" content=\"Maglione Materica Marrone \u27a4 Acquista online su Secondastrada.com Maglione Materica Marrone \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.secondastrada.com\/it\/maglione-materica-marrone-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Seconda Strada\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T12:19:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2025\/11\/D018-OA_MORO_AI25_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maglione Materica Marrone - Acquista online! - Seconda Strada","description":"Maglione Materica Marrone \u27a4 Acquista online su Secondastrada.com Maglione Materica Marrone \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.secondastrada.com\/it\/maglione-materica-marrone-4\/","og_locale":"it_IT","og_type":"article","og_title":"Maglione Materica Marrone - Acquista online! - Seconda Strada","og_description":"Maglione Materica Marrone \u27a4 Acquista online su Secondastrada.com Maglione Materica Marrone \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","og_url":"https:\/\/www.secondastrada.com\/it\/maglione-materica-marrone-4\/","og_site_name":"Seconda Strada","article_modified_time":"2026-03-25T12:19:42+00:00","og_image":[{"width":1000,"height":1300,"url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2025\/11\/D018-OA_MORO_AI25_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.secondastrada.com\/it\/maglione-materica-marrone-4\/","url":"https:\/\/www.secondastrada.com\/it\/maglione-materica-marrone-4\/","name":"Maglione Materica Marrone - Acquista online! - Seconda Strada","isPartOf":{"@id":"https:\/\/www.secondastrada.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.secondastrada.com\/it\/maglione-materica-marrone-4\/#primaryimage"},"image":{"@id":"https:\/\/www.secondastrada.com\/it\/maglione-materica-marrone-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2025\/11\/D018-OA_MORO_AI25_1.jpg","datePublished":"2025-11-20T09:41:17+00:00","dateModified":"2026-03-25T12:19:42+00:00","description":"Maglione Materica Marrone \u27a4 Acquista online su Secondastrada.com Maglione Materica Marrone \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","breadcrumb":{"@id":"https:\/\/www.secondastrada.com\/it\/maglione-materica-marrone-4\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.secondastrada.com\/it\/maglione-materica-marrone-4\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secondastrada.com\/it\/maglione-materica-marrone-4\/#primaryimage","url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2025\/11\/D018-OA_MORO_AI25_1.jpg","contentUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2025\/11\/D018-OA_MORO_AI25_1.jpg","width":1000,"height":1300,"caption":"D018-OA_MORO_AI25"},{"@type":"BreadcrumbList","@id":"https:\/\/www.secondastrada.com\/it\/maglione-materica-marrone-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.secondastrada.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.secondastrada.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Donna","item":"https:\/\/www.secondastrada.com\/it\/collezione-donna\/"},{"@type":"ListItem","position":4,"name":"Abbigliamento","item":"https:\/\/www.secondastrada.com\/it\/collezione-donna\/abbigliamento-donna\/"},{"@type":"ListItem","position":5,"name":"Maglieria","item":"https:\/\/www.secondastrada.com\/it\/collezione-donna\/abbigliamento-donna\/maglie-da-donna\/"},{"@type":"ListItem","position":6,"name":"Maglie a manica lunga","item":"https:\/\/www.secondastrada.com\/it\/collezione-donna\/abbigliamento-donna\/maglie-da-donna\/maglie-a-manica-lunga-da-donna\/"},{"@type":"ListItem","position":7,"name":"Maglione Materica Marrone"}]},{"@type":"WebSite","@id":"https:\/\/www.secondastrada.com\/it\/#website","url":"https:\/\/www.secondastrada.com\/it\/","name":"Seconda Strada","description":"","publisher":{"@id":"https:\/\/www.secondastrada.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.secondastrada.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.secondastrada.com\/it\/#organization","name":"Seconda Strada","url":"https:\/\/www.secondastrada.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secondastrada.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2023\/11\/secondastrada-logo.svg","contentUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2023\/11\/secondastrada-logo.svg","width":353,"height":47,"caption":"Seconda Strada"},"image":{"@id":"https:\/\/www.secondastrada.com\/it\/#\/schema\/logo\/image\/"}}]}},"df_price":15.996,"df_sale_price":"","df_regular_price":15.996,"df_image_link":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2025\/11\/D018-OA_MORO_AI25_1-300x300.jpg","_links":{"self":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product\/320115"}],"collection":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/media\/319386"}],"wp:attachment":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/media?parent=320115"}],"wp:term":[{"taxonomy":"ss_brand","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_brand?post=320115"},{"taxonomy":"ss_promo","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_promo?post=320115"},{"taxonomy":"ss_season","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_season?post=320115"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product_cat?post=320115"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product_tag?post=320115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}