{"id":339116,"date":"2026-02-26T16:14:08","date_gmt":"2026-02-26T15:14:08","guid":{"rendered":"https:\/\/www.secondastrada.com\/it\/t-shirt-guess-blu-8\/"},"modified":"2026-07-09T17:09:51","modified_gmt":"2026-07-09T15:09:51","slug":"t-shirt-guess-blu-8","status":"publish","type":"product","link":"https:\/\/www.secondastrada.com\/it\/t-shirt-guess-blu-8\/","title":{"rendered":"T-shirt Guess Blu"},"content":{"rendered":"<p><b>T-shirt GUESS Blu da uomo<\/b><br \/>\nLa T-shirt GUESS Blu \u00e8 il capo ideale per chi cerca uno stile essenziale ma ricercato nei dettagli. Il colore blu, intenso e versatile, si presta a numerosi abbinamenti e dona profondit\u00e0 al look, rendendolo adatto sia al tempo libero sia a occasioni informali. Realizzata in 83% poliestere, 15% viscosa e 2% elastane, offre una piacevole combinazione di morbidezza, leggerezza ed elasticit\u00e0. \u00c8 una T-shirt da uomo adatta alla stagione primavera estate, perfetta per accompagnarti con comfort nelle giornate pi\u00f9 miti.<br \/>Il design si distingue per un tessuto lavorato, girocollo classico, dettagli che aggiungono personalit\u00e0 mantenendo una linea pulita e contemporanea. La vestibilit\u00e0 \u00e8 regolare, pensata per garantire equilibrio tra comodit\u00e0 e struttura. Il modello \u00e8 alto 187 cm e indossa la taglia L, un riferimento utile per orientarti nella scelta della misura pi\u00f9 adatta.<br \/>Puoi indossarla nel tempo libero, di giorno per un look rilassato oppure di sera per un\u2019uscita informale in cui vuoi sentirti curato ma a tuo agio. Si abbina facilmente a jeans e sneakers per uno stile dinamico e attuale, oppure a pantaloni chino per un outfit pi\u00f9 ricercato ma sempre disinvolto. La T-shirt GUESS Blu diventa cos\u00ec un elemento versatile e affidabile del tuo guardaroba.<br \/>Scegli un capo firmato che unisce qualit\u00e0 dei materiali e stile contemporaneo.<br \/>Tutti i prodotti su SecondaStrada.com sono originali. Codice articolo: M5YP22 KCWO2 SB.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>T-shirt GUESS Blu da uomo La T-shirt GUESS Blu \u00e8 il capo ideale per chi cerca uno stile essenziale ma ricercato nei dettagli. Il colore blu, intenso e versatile, si presta a numerosi abbinamenti e dona profondit\u00e0 al look, rendendolo adatto sia al tempo libero sia a occasioni informali. Realizzata in 83% poliestere, 15% viscosa&#8230;<\/p>\n","protected":false},"featured_media":339872,"template":"","meta":{"inline_featured_image":false},"ss_brand":[1287],"ss_promo":[2230],"ss_season":[2531],"product_cat":[1332,1479,2276,1714],"product_tag":[1739],"class_list":{"0":"post-339116","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"ss_brand-guess-uomo","7":"ss_promo-saldi-uomo","8":"ss_season-pe26","9":"product_cat-abbigliamento-uomo","10":"product_cat-t-shirt-da-uomo","11":"product_cat-t-shirt-in-cotone-da-uomo","12":"product_cat-collezione-uomo","13":"product_tag-t-shirt-guess-uomo","15":"first","16":"instock","17":"sale","18":"shipping-taxable","19":"purchasable","20":"product-type-variable","21":"has-default-attributes"},"acf":{"ss_brand":[{"term_id":1287,"name":"GUESS","slug":"guess-uomo","term_group":0,"term_taxonomy_id":1287,"taxonomy":"ss_brand","description":"<strong>Abbigliamento uomo Guess scontato: osa di pi\u00f9!<\/strong> Mixare raffinatezza francese e spirito californiano in uno <strong>stile originale<\/strong>? Si pu\u00f2 con <strong>Guess<\/strong>! Il brand infatti ha origine negli Stati Uniti dall'idea di due fratelli francesi. Guess crea collezioni di <strong>abbigliamento e accessori per uomo<\/strong> che non passano mai di moda: anche i capi pi\u00f9 classici hanno uno stile inedito! Scopri sul nostro store online la collezione di abbigliamento e accessori da uomo pi\u00f9 glamour che c\u2019\u00e8 a <strong>prezzi imbattibili<\/strong>!","parent":1268,"count":233,"filter":"raw"}],"ss_promo":[2230],"ss_season":[{"term_id":2531,"name":"PE26","slug":"pe26","term_group":0,"term_taxonomy_id":2531,"taxonomy":"ss_season","description":"","parent":0,"count":2671,"filter":"raw"}],"ss_old_price":"55,00","ss_omnibus_price":"0,00","ss_style_advice":"<p><b>T-shirt GUESS Blu da uomo<\/b><br \/>\nLa T-shirt GUESS Blu \u00e8 il capo ideale per chi cerca uno stile essenziale ma ricercato nei dettagli. Il colore blu, intenso e versatile, si presta a numerosi abbinamenti e dona profondit\u00e0 al look, rendendolo adatto sia al tempo libero sia a occasioni informali. Realizzata in 83% poliestere, 15% viscosa e 2% elastane, offre una piacevole combinazione di morbidezza, leggerezza ed elasticit\u00e0. \u00c8 una T-shirt da uomo adatta alla stagione primavera estate, perfetta per accompagnarti con comfort nelle giornate pi\u00f9 miti.<br \/>Il design si distingue per un tessuto lavorato, girocollo classico, dettagli che aggiungono personalit\u00e0 mantenendo una linea pulita e contemporanea. La vestibilit\u00e0 \u00e8 regolare, pensata per garantire equilibrio tra comodit\u00e0 e struttura. Il modello \u00e8 alto 187 cm e indossa la taglia L, un riferimento utile per orientarti nella scelta della misura pi\u00f9 adatta.<br \/>Puoi indossarla nel tempo libero, di giorno per un look rilassato oppure di sera per un\u2019uscita informale in cui vuoi sentirti curato ma a tuo agio. Si abbina facilmente a jeans e sneakers per uno stile dinamico e attuale, oppure a pantaloni chino per un outfit pi\u00f9 ricercato ma sempre disinvolto. La T-shirt GUESS Blu diventa cos\u00ec un elemento versatile e affidabile del tuo guardaroba.<br \/>Scegli un capo firmato che unisce qualit\u00e0 dei materiali e stile contemporaneo.<br \/>Tutti i prodotti su SecondaStrada.com sono originali. Codice articolo: M5YP22 KCWO2 SB.<\/p>\n","ss_composition":"<p>83% poliestere 15% viscosa 2% elastane<\/p>\n","ss_fit":"<p>Il modello \u00e8 alto 187 cm e veste la taglia L. La vestibilit\u00e0 del capo \u00e8 regolare.<\/p>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>T-shirt Guess Blu - Acquista online! - Seconda Strada<\/title>\n<meta name=\"description\" content=\"T-shirt Guess Blu \u27a4 Acquista online su Secondastrada.com T-shirt Guess Blu \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.secondastrada.com\/it\/t-shirt-guess-blu-8\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T-shirt Guess Blu - Acquista online! - Seconda Strada\" \/>\n<meta property=\"og:description\" content=\"T-shirt Guess Blu \u27a4 Acquista online su Secondastrada.com T-shirt Guess Blu \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.secondastrada.com\/it\/t-shirt-guess-blu-8\/\" \/>\n<meta property=\"og:site_name\" content=\"Seconda Strada\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T15:09:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/02\/M5YP22-KCWO2-SB_ENDLESS-BLUE-MULTI_PE26_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T-shirt Guess Blu - Acquista online! - Seconda Strada","description":"T-shirt Guess Blu \u27a4 Acquista online su Secondastrada.com T-shirt Guess Blu \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.secondastrada.com\/it\/t-shirt-guess-blu-8\/","og_locale":"it_IT","og_type":"article","og_title":"T-shirt Guess Blu - Acquista online! - Seconda Strada","og_description":"T-shirt Guess Blu \u27a4 Acquista online su Secondastrada.com T-shirt Guess Blu \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","og_url":"https:\/\/www.secondastrada.com\/it\/t-shirt-guess-blu-8\/","og_site_name":"Seconda Strada","article_modified_time":"2026-07-09T15:09:51+00:00","og_image":[{"width":1000,"height":1300,"url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/02\/M5YP22-KCWO2-SB_ENDLESS-BLUE-MULTI_PE26_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.secondastrada.com\/it\/t-shirt-guess-blu-8\/","url":"https:\/\/www.secondastrada.com\/it\/t-shirt-guess-blu-8\/","name":"T-shirt Guess Blu - Acquista online! - Seconda Strada","isPartOf":{"@id":"https:\/\/www.secondastrada.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.secondastrada.com\/it\/t-shirt-guess-blu-8\/#primaryimage"},"image":{"@id":"https:\/\/www.secondastrada.com\/it\/t-shirt-guess-blu-8\/#primaryimage"},"thumbnailUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/02\/M5YP22-KCWO2-SB_ENDLESS-BLUE-MULTI_PE26_1.jpg","datePublished":"2026-02-26T15:14:08+00:00","dateModified":"2026-07-09T15:09:51+00:00","description":"T-shirt Guess Blu \u27a4 Acquista online su Secondastrada.com T-shirt Guess Blu \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","breadcrumb":{"@id":"https:\/\/www.secondastrada.com\/it\/t-shirt-guess-blu-8\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.secondastrada.com\/it\/t-shirt-guess-blu-8\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secondastrada.com\/it\/t-shirt-guess-blu-8\/#primaryimage","url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/02\/M5YP22-KCWO2-SB_ENDLESS-BLUE-MULTI_PE26_1.jpg","contentUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/02\/M5YP22-KCWO2-SB_ENDLESS-BLUE-MULTI_PE26_1.jpg","width":1000,"height":1300,"caption":"M5YP22-KCWO2-SB_ENDLESS-BLUE-MULTI_PE26"},{"@type":"BreadcrumbList","@id":"https:\/\/www.secondastrada.com\/it\/t-shirt-guess-blu-8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.secondastrada.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.secondastrada.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Uomo","item":"https:\/\/www.secondastrada.com\/it\/collezione-uomo\/"},{"@type":"ListItem","position":4,"name":"Abbigliamento","item":"https:\/\/www.secondastrada.com\/it\/collezione-uomo\/abbigliamento-uomo\/"},{"@type":"ListItem","position":5,"name":"T-shirt","item":"https:\/\/www.secondastrada.com\/it\/collezione-uomo\/abbigliamento-uomo\/t-shirt-da-uomo\/"},{"@type":"ListItem","position":6,"name":"T-shirt in cotone","item":"https:\/\/www.secondastrada.com\/it\/collezione-uomo\/abbigliamento-uomo\/t-shirt-da-uomo\/t-shirt-in-cotone-da-uomo\/"},{"@type":"ListItem","position":7,"name":"T-shirt Guess Blu"}]},{"@type":"WebSite","@id":"https:\/\/www.secondastrada.com\/it\/#website","url":"https:\/\/www.secondastrada.com\/it\/","name":"Seconda Strada","description":"","publisher":{"@id":"https:\/\/www.secondastrada.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.secondastrada.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.secondastrada.com\/it\/#organization","name":"Seconda Strada","url":"https:\/\/www.secondastrada.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secondastrada.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2023\/11\/secondastrada-logo.svg","contentUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2023\/11\/secondastrada-logo.svg","width":353,"height":47,"caption":"Seconda Strada"},"image":{"@id":"https:\/\/www.secondastrada.com\/it\/#\/schema\/logo\/image\/"}}]}},"df_price":27.5,"df_sale_price":"","df_regular_price":27.5,"df_image_link":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/02\/M5YP22-KCWO2-SB_ENDLESS-BLUE-MULTI_PE26_1-300x300.jpg","_links":{"self":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product\/339116"}],"collection":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/media\/339872"}],"wp:attachment":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/media?parent=339116"}],"wp:term":[{"taxonomy":"ss_brand","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_brand?post=339116"},{"taxonomy":"ss_promo","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_promo?post=339116"},{"taxonomy":"ss_season","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_season?post=339116"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product_cat?post=339116"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product_tag?post=339116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}