{"id":379095,"date":"2026-05-29T15:55:51","date_gmt":"2026-05-29T13:55:51","guid":{"rendered":"https:\/\/www.secondastrada.com\/it\/bermuda-armani-exchange-nero-2\/"},"modified":"2026-07-13T19:53:39","modified_gmt":"2026-07-13T17:53:39","slug":"bermuda-armani-exchange-nero-2","status":"publish","type":"product","link":"https:\/\/www.secondastrada.com\/it\/bermuda-armani-exchange-nero-2\/","title":{"rendered":"Bermuda Armani Exchange Nero"},"content":{"rendered":"<p><b>Bermuda ARMANI EXCHANGE Nero da Uomo<\/b><br \/>\nIl bermuda ARMANI EXCHANGE nero da uomo \u00e8 il capo ideale per vivere la stagione primavera estate con comfort e stile contemporaneo. Realizzato in un tessuto morbido composto da cotone ed elastina, offre una vestibilit\u00e0 regolare che accompagna i movimenti con naturalezza, garantendo praticit\u00e0 durante tutta la giornata. Il tessuto a rilievo aggiunge personalit\u00e0 al design e dona un tocco moderno capace di valorizzare anche gli outfit pi\u00f9 essenziali.<br \/>Il colore nero rende questo bermuda estremamente versatile e facile da abbinare, perfetto per creare look casual e curati allo stesso tempo. La linea pulita e il design minimal rispecchiano lo stile dinamico di ARMANI EXCHANGE, ideale per chi cerca un capo pratico senza rinunciare all\u2019eleganza informale.<br \/>Questo bermuda da uomo pu\u00f2 essere indossato nel tempo libero con una polo abbinata e sneakers per un outfit fresco e moderno, perfetto per le giornate pi\u00f9 calde, le passeggiate in citt\u00e0 o i momenti di relax del weekend. Grazie al tessuto confortevole e alla vestibilit\u00e0 regolare, rappresenta una scelta versatile da utilizzare facilmente in diverse occasioni quotidiane.<br \/>Il modello \u00e8 alto 187 cm e indossa la taglia L. La vestibilit\u00e0 del capo \u00e8 regolare.<br \/><b>Codice articolo: XM002348AF21860 OB<\/b><br \/>Tutti i prodotti presenti su SecondaStrada.com sono originali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bermuda ARMANI EXCHANGE Nero da Uomo Il bermuda ARMANI EXCHANGE nero da uomo \u00e8 il capo ideale per vivere la stagione primavera estate con comfort e stile contemporaneo. Realizzato in un tessuto morbido composto da cotone ed elastina, offre una vestibilit\u00e0 regolare che accompagna i movimenti con naturalezza, garantendo praticit\u00e0 durante tutta la giornata. Il&#8230;<\/p>\n","protected":false},"featured_media":380013,"template":"","meta":{"inline_featured_image":false},"ss_brand":[1873],"ss_promo":[],"ss_season":[2531],"product_cat":[1332,1551,2538,1714],"product_tag":[2412],"class_list":{"0":"post-379095","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"ss_brand-armani-exchange-uomo","7":"ss_season-pe26","8":"product_cat-abbigliamento-uomo","9":"product_cat-bermuda-da-uomo","10":"product_cat-set-coordinati-da-uomo","11":"product_cat-collezione-uomo","12":"product_tag-look-casual-uomo","14":"first","15":"instock","16":"shipping-taxable","17":"purchasable","18":"product-type-variable","19":"has-default-attributes"},"acf":{"ss_brand":[{"term_id":1873,"name":"ARMANI EXCHANGE","slug":"armani-exchange-uomo","term_group":0,"term_taxonomy_id":1873,"taxonomy":"ss_brand","description":"Armani Exchange \u00e8 il brand giovane e casual che conquista con i suoi colori e la qualit\u00e0 unica","parent":1268,"count":31,"filter":"raw"}],"ss_promo":false,"ss_season":[{"term_id":2531,"name":"PE26","slug":"pe26","term_group":0,"term_taxonomy_id":2531,"taxonomy":"ss_season","description":"","parent":0,"count":2671,"filter":"raw"}],"ss_old_price":"100,00","ss_omnibus_price":"0,00","ss_style_advice":"<p><b>Bermuda ARMANI EXCHANGE Nero da Uomo<\/b><br \/>\nIl bermuda ARMANI EXCHANGE nero da uomo \u00e8 il capo ideale per vivere la stagione primavera estate con comfort e stile contemporaneo. Realizzato in un tessuto morbido composto da cotone ed elastina, offre una vestibilit\u00e0 regolare che accompagna i movimenti con naturalezza, garantendo praticit\u00e0 durante tutta la giornata. Il tessuto a rilievo aggiunge personalit\u00e0 al design e dona un tocco moderno capace di valorizzare anche gli outfit pi\u00f9 essenziali.<br \/>Il colore nero rende questo bermuda estremamente versatile e facile da abbinare, perfetto per creare look casual e curati allo stesso tempo. La linea pulita e il design minimal rispecchiano lo stile dinamico di ARMANI EXCHANGE, ideale per chi cerca un capo pratico senza rinunciare all\u2019eleganza informale.<br \/>Questo bermuda da uomo pu\u00f2 essere indossato nel tempo libero con una polo abbinata e sneakers per un outfit fresco e moderno, perfetto per le giornate pi\u00f9 calde, le passeggiate in citt\u00e0 o i momenti di relax del weekend. Grazie al tessuto confortevole e alla vestibilit\u00e0 regolare, rappresenta una scelta versatile da utilizzare facilmente in diverse occasioni quotidiane.<br \/>Il modello \u00e8 alto 187 cm e indossa la taglia L. La vestibilit\u00e0 del capo \u00e8 regolare.<br \/><b>Codice articolo: XM002348AF21860 OB<\/b><br \/>Tutti i prodotti presenti su SecondaStrada.com sono originali.<\/p>\n","ss_composition":"<p>77% cotone 23% elastina<\/p>\n","ss_fit":"<p>Il modello \u00e8 alto 187 cm e veste la taglia L. La vestibilit\u00e0 del capo \u00e8 regolare.<\/p>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bermuda Armani Exchange Nero - Acquista online! - Seconda Strada<\/title>\n<meta name=\"description\" content=\"Bermuda Armani Exchange Nero \u27a4 Acquista online su Secondastrada.com Bermuda Armani Exchange Nero \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.secondastrada.com\/it\/bermuda-armani-exchange-nero-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bermuda Armani Exchange Nero - Acquista online! - Seconda Strada\" \/>\n<meta property=\"og:description\" content=\"Bermuda Armani Exchange Nero \u27a4 Acquista online su Secondastrada.com Bermuda Armani Exchange Nero \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.secondastrada.com\/it\/bermuda-armani-exchange-nero-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Seconda Strada\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T17:53:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/05\/XM002348AF21860-OB_UB10_PE26_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bermuda Armani Exchange Nero - Acquista online! - Seconda Strada","description":"Bermuda Armani Exchange Nero \u27a4 Acquista online su Secondastrada.com Bermuda Armani Exchange Nero \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.secondastrada.com\/it\/bermuda-armani-exchange-nero-2\/","og_locale":"it_IT","og_type":"article","og_title":"Bermuda Armani Exchange Nero - Acquista online! - Seconda Strada","og_description":"Bermuda Armani Exchange Nero \u27a4 Acquista online su Secondastrada.com Bermuda Armani Exchange Nero \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","og_url":"https:\/\/www.secondastrada.com\/it\/bermuda-armani-exchange-nero-2\/","og_site_name":"Seconda Strada","article_modified_time":"2026-07-13T17:53:39+00:00","og_image":[{"width":1000,"height":1300,"url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/05\/XM002348AF21860-OB_UB10_PE26_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.secondastrada.com\/it\/bermuda-armani-exchange-nero-2\/","url":"https:\/\/www.secondastrada.com\/it\/bermuda-armani-exchange-nero-2\/","name":"Bermuda Armani Exchange Nero - Acquista online! - Seconda Strada","isPartOf":{"@id":"https:\/\/www.secondastrada.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.secondastrada.com\/it\/bermuda-armani-exchange-nero-2\/#primaryimage"},"image":{"@id":"https:\/\/www.secondastrada.com\/it\/bermuda-armani-exchange-nero-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/05\/XM002348AF21860-OB_UB10_PE26_1.jpg","datePublished":"2026-05-29T13:55:51+00:00","dateModified":"2026-07-13T17:53:39+00:00","description":"Bermuda Armani Exchange Nero \u27a4 Acquista online su Secondastrada.com Bermuda Armani Exchange Nero \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","breadcrumb":{"@id":"https:\/\/www.secondastrada.com\/it\/bermuda-armani-exchange-nero-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.secondastrada.com\/it\/bermuda-armani-exchange-nero-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secondastrada.com\/it\/bermuda-armani-exchange-nero-2\/#primaryimage","url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/05\/XM002348AF21860-OB_UB10_PE26_1.jpg","contentUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/05\/XM002348AF21860-OB_UB10_PE26_1.jpg","width":1000,"height":1300,"caption":"XM002348AF21860-OB_UB10_PE26"},{"@type":"BreadcrumbList","@id":"https:\/\/www.secondastrada.com\/it\/bermuda-armani-exchange-nero-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.secondastrada.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.secondastrada.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Uomo","item":"https:\/\/www.secondastrada.com\/it\/collezione-uomo\/"},{"@type":"ListItem","position":4,"name":"Abbigliamento","item":"https:\/\/www.secondastrada.com\/it\/collezione-uomo\/abbigliamento-uomo\/"},{"@type":"ListItem","position":5,"name":"Bermuda","item":"https:\/\/www.secondastrada.com\/it\/collezione-uomo\/abbigliamento-uomo\/bermuda-da-uomo\/"},{"@type":"ListItem","position":6,"name":"Bermuda Armani Exchange Nero"}]},{"@type":"WebSite","@id":"https:\/\/www.secondastrada.com\/it\/#website","url":"https:\/\/www.secondastrada.com\/it\/","name":"Seconda Strada","description":"","publisher":{"@id":"https:\/\/www.secondastrada.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.secondastrada.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.secondastrada.com\/it\/#organization","name":"Seconda Strada","url":"https:\/\/www.secondastrada.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secondastrada.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2023\/11\/secondastrada-logo.svg","contentUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2023\/11\/secondastrada-logo.svg","width":353,"height":47,"caption":"Seconda Strada"},"image":{"@id":"https:\/\/www.secondastrada.com\/it\/#\/schema\/logo\/image\/"}}]}},"df_price":69.99,"df_sale_price":"","df_regular_price":69.99,"df_image_link":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/05\/XM002348AF21860-OB_UB10_PE26_1-300x300.jpg","_links":{"self":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product\/379095"}],"collection":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/media\/380013"}],"wp:attachment":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/media?parent=379095"}],"wp:term":[{"taxonomy":"ss_brand","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_brand?post=379095"},{"taxonomy":"ss_promo","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_promo?post=379095"},{"taxonomy":"ss_season","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_season?post=379095"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product_cat?post=379095"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product_tag?post=379095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}