{"id":379745,"date":"2026-06-03T10:41:28","date_gmt":"2026-06-03T08:41:28","guid":{"rendered":"https:\/\/www.secondastrada.com\/it\/t-shirt-calvin-klein-nera-5\/"},"modified":"2026-07-14T22:06:38","modified_gmt":"2026-07-14T20:06:38","slug":"t-shirt-calvin-klein-nera-5","status":"publish","type":"product","link":"https:\/\/www.secondastrada.com\/it\/t-shirt-calvin-klein-nera-5\/","title":{"rendered":"T-shirt Calvin Klein Nera"},"content":{"rendered":"<p><b>T-shirt CALVIN KLEIN nera da uomo con piccolo logo a contrasto<\/b><br \/>\nLa <b>T-shirt CALVIN KLEIN Nera<\/b> \u00e8 il capo perfetto per chi ama uno stile essenziale ma curato nei dettagli. Realizzata in <b>100% cotone<\/b>, offre una piacevole sensazione di comfort e morbidezza sulla pelle, accompagnandoti con praticit\u00e0 durante tutto l&#8217;anno. Grazie alla sua versatilit\u00e0, \u00e8 una <b>T-shirt adatta in tutte le stagioni<\/b>, ideale da indossare sia nei mesi pi\u00f9 caldi sia come base per outfit stratificati nelle giornate pi\u00f9 fresche.<br \/>Il design minimal \u00e8 arricchito da un <b>piccolo logo a contrasto<\/b>, dettaglio discreto che valorizza il carattere contemporaneo del capo e richiama l&#8217;inconfondibile identit\u00e0 del brand CALVIN KLEIN. La vestibilit\u00e0 regolare garantisce un fit comodo e naturale, adatto a diverse fisicit\u00e0 e perfetto per un utilizzo quotidiano. Il modello \u00e8 alto 187 cm e indossa la taglia L, mostrando una linea equilibrata e versatile.<br \/>Questa <b>T-shirt con piccolo logo a contrasto<\/b> \u00e8 ideale per il tempo libero, per una passeggiata in citt\u00e0, un viaggio o per affrontare con stile gli impegni di ogni giorno. Per un look casual e dinamico puoi abbinarla a bermuda e sneakers, mentre con jeans e scarpe sportive otterrai un outfit semplice ma sempre attuale.<br \/>La qualit\u00e0 del cotone, unita al design pulito e facilmente abbinabile, rende questa T-shirt una scelta indispensabile per chi cerca un capo pratico, moderno e destinato a durare nel tempo.<br \/>Tutti i prodotti in vendita su Seconda Strada sono accuratamente selezionati per garantire autenticit\u00e0 e qualit\u00e0.<br \/><b>Codice articolo: LV14RF852G OB<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>T-shirt CALVIN KLEIN nera da uomo con piccolo logo a contrasto La T-shirt CALVIN KLEIN Nera \u00e8 il capo perfetto per chi ama uno stile essenziale ma curato nei dettagli. Realizzata in 100% cotone, offre una piacevole sensazione di comfort e morbidezza sulla pelle, accompagnandoti con praticit\u00e0 durante tutto l&#8217;anno. Grazie alla sua versatilit\u00e0, \u00e8&#8230;<\/p>\n","protected":false},"featured_media":380328,"template":"","meta":{"inline_featured_image":false},"ss_brand":[1305],"ss_promo":[2230],"ss_season":[2531],"product_cat":[1332,1479,2276,1714],"product_tag":[1751],"class_list":{"0":"post-379745","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"ss_brand-calvin-klein-uomo","7":"ss_promo-saldi-uomo","8":"ss_season-pe26","9":"product_cat-abbigliamento-uomo","10":"product_cat-t-shirt-da-uomo","11":"product_cat-t-shirt-in-cotone-da-uomo","12":"product_cat-collezione-uomo","13":"product_tag-t-shirt-calvin-klein-uomo","15":"first","16":"instock","17":"sale","18":"shipping-taxable","19":"purchasable","20":"product-type-variable","21":"has-default-attributes"},"acf":{"ss_brand":[{"term_id":1305,"name":"CALVIN KLEIN","slug":"calvin-klein-uomo","term_group":0,"term_taxonomy_id":1305,"taxonomy":"ss_brand","description":"Calvin Klein si afferma nell\u2019universo casual con un design privo di orpelli e funzionale. Vestiti di semplicit\u00e0 con le offerte che abbiamo preparato per te!\u00a0Acquista online su SecondaStrada.com <strong>abbigliamento da uomo CALVIN KLEIN scontatissimo<\/strong>!","parent":1268,"count":371,"filter":"raw"}],"ss_promo":[2230],"ss_season":[{"term_id":2531,"name":"PE26","slug":"pe26","term_group":0,"term_taxonomy_id":2531,"taxonomy":"ss_season","description":"","parent":0,"count":2670,"filter":"raw"}],"ss_old_price":"39,90","ss_omnibus_price":"0,00","ss_style_advice":"<p><b>T-shirt CALVIN KLEIN nera da uomo con piccolo logo a contrasto<\/b><br \/>\nLa <b>T-shirt CALVIN KLEIN Nera<\/b> \u00e8 il capo perfetto per chi ama uno stile essenziale ma curato nei dettagli. Realizzata in <b>100% cotone<\/b>, offre una piacevole sensazione di comfort e morbidezza sulla pelle, accompagnandoti con praticit\u00e0 durante tutto l&#8217;anno. Grazie alla sua versatilit\u00e0, \u00e8 una <b>T-shirt adatta in tutte le stagioni<\/b>, ideale da indossare sia nei mesi pi\u00f9 caldi sia come base per outfit stratificati nelle giornate pi\u00f9 fresche.<br \/>Il design minimal \u00e8 arricchito da un <b>piccolo logo a contrasto<\/b>, dettaglio discreto che valorizza il carattere contemporaneo del capo e richiama l&#8217;inconfondibile identit\u00e0 del brand CALVIN KLEIN. La vestibilit\u00e0 regolare garantisce un fit comodo e naturale, adatto a diverse fisicit\u00e0 e perfetto per un utilizzo quotidiano. Il modello \u00e8 alto 187 cm e indossa la taglia L, mostrando una linea equilibrata e versatile.<br \/>Questa <b>T-shirt con piccolo logo a contrasto<\/b> \u00e8 ideale per il tempo libero, per una passeggiata in citt\u00e0, un viaggio o per affrontare con stile gli impegni di ogni giorno. Per un look casual e dinamico puoi abbinarla a bermuda e sneakers, mentre con jeans e scarpe sportive otterrai un outfit semplice ma sempre attuale.<br \/>La qualit\u00e0 del cotone, unita al design pulito e facilmente abbinabile, rende questa T-shirt una scelta indispensabile per chi cerca un capo pratico, moderno e destinato a durare nel tempo.<br \/>Tutti i prodotti in vendita su Seconda Strada sono accuratamente selezionati per garantire autenticit\u00e0 e qualit\u00e0.<br \/><b>Codice articolo: LV14RF852G OB<\/b><\/p>\n","ss_composition":"<p>100% cotone<\/p>\n","ss_fit":"<p>Il modello \u00e8 alto 187 cm e veste la taglia L. La vestibilit\u00e0 del capo \u00e8 regolare.<\/p>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>T-shirt Calvin Klein Nera - Acquista online! - Seconda Strada<\/title>\n<meta name=\"description\" content=\"T-shirt Calvin Klein Nera \u27a4 Acquista online su Secondastrada.com T-shirt Calvin Klein Nera \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.secondastrada.com\/it\/t-shirt-calvin-klein-nera-5\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T-shirt Calvin Klein Nera - Acquista online! - Seconda Strada\" \/>\n<meta property=\"og:description\" content=\"T-shirt Calvin Klein Nera \u27a4 Acquista online su Secondastrada.com T-shirt Calvin Klein Nera \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.secondastrada.com\/it\/t-shirt-calvin-klein-nera-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Seconda Strada\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T20:06:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/06\/LV14RF852G-OB_UB1_PE26_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T-shirt Calvin Klein Nera - Acquista online! - Seconda Strada","description":"T-shirt Calvin Klein Nera \u27a4 Acquista online su Secondastrada.com T-shirt Calvin Klein Nera \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.secondastrada.com\/it\/t-shirt-calvin-klein-nera-5\/","og_locale":"it_IT","og_type":"article","og_title":"T-shirt Calvin Klein Nera - Acquista online! - Seconda Strada","og_description":"T-shirt Calvin Klein Nera \u27a4 Acquista online su Secondastrada.com T-shirt Calvin Klein Nera \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","og_url":"https:\/\/www.secondastrada.com\/it\/t-shirt-calvin-klein-nera-5\/","og_site_name":"Seconda Strada","article_modified_time":"2026-07-14T20:06:38+00:00","og_image":[{"width":1000,"height":1300,"url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/06\/LV14RF852G-OB_UB1_PE26_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.secondastrada.com\/it\/t-shirt-calvin-klein-nera-5\/","url":"https:\/\/www.secondastrada.com\/it\/t-shirt-calvin-klein-nera-5\/","name":"T-shirt Calvin Klein Nera - Acquista online! - Seconda Strada","isPartOf":{"@id":"https:\/\/www.secondastrada.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.secondastrada.com\/it\/t-shirt-calvin-klein-nera-5\/#primaryimage"},"image":{"@id":"https:\/\/www.secondastrada.com\/it\/t-shirt-calvin-klein-nera-5\/#primaryimage"},"thumbnailUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/06\/LV14RF852G-OB_UB1_PE26_1.jpg","datePublished":"2026-06-03T08:41:28+00:00","dateModified":"2026-07-14T20:06:38+00:00","description":"T-shirt Calvin Klein Nera \u27a4 Acquista online su Secondastrada.com T-shirt Calvin Klein Nera \u2714\ufe0f Spedizione veloce entro 24h in tutta Italia \u2714\ufe0f Sconto sul tuo primo acquisto","breadcrumb":{"@id":"https:\/\/www.secondastrada.com\/it\/t-shirt-calvin-klein-nera-5\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.secondastrada.com\/it\/t-shirt-calvin-klein-nera-5\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secondastrada.com\/it\/t-shirt-calvin-klein-nera-5\/#primaryimage","url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/06\/LV14RF852G-OB_UB1_PE26_1.jpg","contentUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/06\/LV14RF852G-OB_UB1_PE26_1.jpg","width":1000,"height":1300,"caption":"LV14RF852G-OB_UB1_PE26"},{"@type":"BreadcrumbList","@id":"https:\/\/www.secondastrada.com\/it\/t-shirt-calvin-klein-nera-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.secondastrada.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.secondastrada.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Uomo","item":"https:\/\/www.secondastrada.com\/it\/collezione-uomo\/"},{"@type":"ListItem","position":4,"name":"Abbigliamento","item":"https:\/\/www.secondastrada.com\/it\/collezione-uomo\/abbigliamento-uomo\/"},{"@type":"ListItem","position":5,"name":"T-shirt","item":"https:\/\/www.secondastrada.com\/it\/collezione-uomo\/abbigliamento-uomo\/t-shirt-da-uomo\/"},{"@type":"ListItem","position":6,"name":"T-shirt in cotone","item":"https:\/\/www.secondastrada.com\/it\/collezione-uomo\/abbigliamento-uomo\/t-shirt-da-uomo\/t-shirt-in-cotone-da-uomo\/"},{"@type":"ListItem","position":7,"name":"T-shirt Calvin Klein Nera"}]},{"@type":"WebSite","@id":"https:\/\/www.secondastrada.com\/it\/#website","url":"https:\/\/www.secondastrada.com\/it\/","name":"Seconda Strada","description":"","publisher":{"@id":"https:\/\/www.secondastrada.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.secondastrada.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.secondastrada.com\/it\/#organization","name":"Seconda Strada","url":"https:\/\/www.secondastrada.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secondastrada.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2023\/11\/secondastrada-logo.svg","contentUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2023\/11\/secondastrada-logo.svg","width":353,"height":47,"caption":"Seconda Strada"},"image":{"@id":"https:\/\/www.secondastrada.com\/it\/#\/schema\/logo\/image\/"}}]}},"df_price":17.495,"df_sale_price":"","df_regular_price":17.495,"df_image_link":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2026\/06\/LV14RF852G-OB_UB1_PE26_1-300x300.jpg","_links":{"self":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product\/379745"}],"collection":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/media\/380328"}],"wp:attachment":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/media?parent=379745"}],"wp:term":[{"taxonomy":"ss_brand","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_brand?post=379745"},{"taxonomy":"ss_promo","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_promo?post=379745"},{"taxonomy":"ss_season","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_season?post=379745"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product_cat?post=379745"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product_tag?post=379745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}