{"id":1252,"count":7,"description":"","link":"https:\/\/www.secondastrada.com\/it\/brand\/donna\/seconda-strada-donna\/","name":"Seconda Strada","slug":"seconda-strada-donna","taxonomy":"ss_brand","parent":1201,"meta":[],"acf":{"title":"SECONDA STRADA","subtitle":"","seo_text":"","alt_image":"","banner":false,"expiration_date":"","logo_brand":false,"ss_tag":false,"inserisci_la_guida_alle_taglie":false,"banner_tablet":false,"banner_mobile":false,"link_promo":"","nascondi":false,"colore":"","percentuale":"","testo_promo":"","sottotitolo_promo":"","categoria_fallback":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Seconda Strada shop online a prezzi outlet - Abbigliamento Donna - Seconda Strada scontato - SCONTI fino al 70% - Seconda Strada<\/title>\n<meta name=\"description\" content=\"Abbigliamento Donna - Seconda Strada \u27a4\u3010SCONTI fino al 70%\u3011\u279c Acquista online al miglior prezzo abbigliamento da Donna - Seconda Strada su Secondastrada.com \u2714\ufe0fSconti fino al 70% \u2714\ufe0fSeconda Strada a prezzi outlet\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.secondastrada.com\/it\/brand\/donna\/seconda-strada-donna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seconda Strada shop online a prezzi outlet - Abbigliamento Donna - Seconda Strada scontato - SCONTI fino al 70% - Seconda Strada\" \/>\n<meta property=\"og:description\" content=\"Abbigliamento Donna - Seconda Strada \u27a4\u3010SCONTI fino al 70%\u3011\u279c Acquista online al miglior prezzo abbigliamento da Donna - Seconda Strada su Secondastrada.com \u2714\ufe0fSconti fino al 70% \u2714\ufe0fSeconda Strada a prezzi outlet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.secondastrada.com\/it\/brand\/donna\/seconda-strada-donna\/\" \/>\n<meta property=\"og:site_name\" content=\"Seconda Strada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seconda Strada shop online a prezzi outlet - Abbigliamento Donna - Seconda Strada scontato - SCONTI fino al 70% - Seconda Strada","description":"Abbigliamento Donna - Seconda Strada \u27a4\u3010SCONTI fino al 70%\u3011\u279c Acquista online al miglior prezzo abbigliamento da Donna - Seconda Strada su Secondastrada.com \u2714\ufe0fSconti fino al 70% \u2714\ufe0fSeconda Strada a prezzi outlet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.secondastrada.com\/it\/brand\/donna\/seconda-strada-donna\/","og_locale":"it_IT","og_type":"article","og_title":"Seconda Strada shop online a prezzi outlet - Abbigliamento Donna - Seconda Strada scontato - SCONTI fino al 70% - Seconda Strada","og_description":"Abbigliamento Donna - Seconda Strada \u27a4\u3010SCONTI fino al 70%\u3011\u279c Acquista online al miglior prezzo abbigliamento da Donna - Seconda Strada su Secondastrada.com \u2714\ufe0fSconti fino al 70% \u2714\ufe0fSeconda Strada a prezzi outlet","og_url":"https:\/\/www.secondastrada.com\/it\/brand\/donna\/seconda-strada-donna\/","og_site_name":"Seconda Strada","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.secondastrada.com\/it\/brand\/donna\/seconda-strada-donna\/","url":"https:\/\/www.secondastrada.com\/it\/brand\/donna\/seconda-strada-donna\/","name":"Seconda Strada shop online a prezzi outlet - Abbigliamento Donna - Seconda Strada scontato - SCONTI fino al 70% - Seconda Strada","isPartOf":{"@id":"https:\/\/www.secondastrada.com\/it\/#website"},"description":"Abbigliamento Donna - Seconda Strada \u27a4\u3010SCONTI fino al 70%\u3011\u279c Acquista online al miglior prezzo abbigliamento da Donna - Seconda Strada su Secondastrada.com \u2714\ufe0fSconti fino al 70% \u2714\ufe0fSeconda Strada a prezzi outlet","breadcrumb":{"@id":"https:\/\/www.secondastrada.com\/it\/brand\/donna\/seconda-strada-donna\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.secondastrada.com\/it\/brand\/donna\/seconda-strada-donna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.secondastrada.com\/it\/"},{"@type":"ListItem","position":2,"name":"Donna","item":"https:\/\/www.secondastrada.com\/it\/brand\/donna\/"},{"@type":"ListItem","position":3,"name":"Seconda Strada"}]},{"@type":"WebSite","@id":"https:\/\/www.secondastrada.com\/it\/#website","url":"https:\/\/www.secondastrada.com\/it\/","name":"Seconda Strada","description":"","publisher":{"@id":"https:\/\/www.secondastrada.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.secondastrada.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.secondastrada.com\/it\/#organization","name":"Seconda Strada","url":"https:\/\/www.secondastrada.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secondastrada.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2023\/11\/secondastrada-logo.svg","contentUrl":"https:\/\/www.secondastrada.com\/wp-content\/uploads\/2023\/11\/secondastrada-logo.svg","width":353,"height":47,"caption":"Seconda Strada"},"image":{"@id":"https:\/\/www.secondastrada.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_brand\/1252"}],"collection":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_brand"}],"about":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/taxonomies\/ss_brand"}],"up":[{"embeddable":true,"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/ss_brand\/1201"}],"wp:post_type":[{"href":"https:\/\/www.secondastrada.com\/it\/wp-json\/wp\/v2\/product?ss_brand=1252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}